{"id":95,"count":27,"description":"","link":"https:\/\/lidajoies.com\/ca\/alianzas-de-boda\/","name":"Aliances de casament","slug":"aliances-de-casament","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":3,"_links":{"self":[{"href":"https:\/\/lidajoies.com\/ca\/wp-json\/wp\/v2\/product_cat\/95","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lidajoies.com\/ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/lidajoies.com\/ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/lidajoies.com\/ca\/wp-json\/wp\/v2\/product?product_cat=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}